{"id":228,"date":"2023-01-11T10:49:13","date_gmt":"2023-01-11T10:49:13","guid":{"rendered":"https:\/\/www.sktperfectdemo.com\/demos\/electrician\/?page_id=9"},"modified":"2026-08-03T20:36:38","modified_gmt":"2026-08-03T18:36:38","slug":"home","status":"publish","type":"page","link":"https:\/\/mbs.group\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"228\" class=\"elementor elementor-228\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1e0056 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1e0056\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e6633b\" data-id=\"7e6633b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97c79df elementor-widget elementor-widget-heading\" data-id=\"97c79df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MBS Group r\u00e9unit deux entreprises compl\u00e9mentaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-293a3e7 elementor-widget elementor-widget-text-editor\" data-id=\"293a3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>pour r\u00e9pondre \u00e0 l\u2019ensemble de vos besoins en \u00e9lectricit\u00e9, maintenance et construction.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e20d84e electrician-pro-section-10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e20d84e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cf151ab electrician-pro-section-10-mid\" data-id=\"3cf151ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3330879c elementor-widget elementor-widget-heading\" data-id=\"3330879c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">N'h\u00e9sitez pas \u00e0 nous contacter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ae1c36d electrician-pro-section-10-inner elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ae1c36d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-51b07c9d electrician-pro-section-10-inner-box1\" data-id=\"51b07c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4693a2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a4693a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Rue+des+Boussines+42%2C+6960+Manhay%2C+Belgique\" tabindex=\"-1\"><img decoding=\"async\" width=\"80\" height=\"78\" src=\"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png\" class=\"attachment-full size-full wp-image-44\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Rue+des+Boussines+42%2C+6960+Manhay%2C+Belgique\">Nous Rejoindre<\/a><\/h3><p class=\"elementor-image-box-description\">Rue des boussines, 42\n6960 Manhay\nBelgique<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4b14a6ad electrician-pro-section-10-inner-box2\" data-id=\"4b14a6ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b321e34 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4b321e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"tel:+3286321207\" tabindex=\"-1\"><img decoding=\"async\" width=\"80\" height=\"78\" src=\"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/phone-icon.png\" class=\"attachment-full size-full wp-image-46\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"tel:+3286321207\">Appelez Nous<\/a><\/h3><p class=\"elementor-image-box-description\">Bureau \n+3286321207  <br>\nGarde +32479268312<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af99112 electrician-pro-section-10-inner-box3\" data-id=\"af99112\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-658f6344 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"658f6344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"mailto:info@mbssolution.be\" tabindex=\"-1\"><img decoding=\"async\" width=\"80\" height=\"78\" src=\"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/mail-icon.png\" class=\"attachment-full size-full wp-image-45\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"mailto:info@mbssolution.be\">Email <\/a><\/h3><p class=\"elementor-image-box-description\">info@mbssolution.be<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5b8b0493 electrician-pro-section-10-inner-box4\" data-id=\"5b8b0493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b8154c4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1b8154c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"78\" src=\"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/time-icon.png\" class=\"attachment-full size-full wp-image-47\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Heure ouverture Bureau<\/h3><p class=\"elementor-image-box-description\">Lun, mar, jeu et ven :<br> 9h \u00e0 16h<br>\nMercredi : ferm\u00e9<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22413f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22413f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04e6b54\" data-id=\"04e6b54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdcc165 elementor-widget elementor-widget-google_maps\" data-id=\"fdcc165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=M.B.S%20Solution&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"M.B.S Solution\"\n\t\t\t\t\taria-label=\"M.B.S Solution\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MBS Group r\u00e9unit deux entreprises compl\u00e9mentaires pour r\u00e9pondre \u00e0 l\u2019ensemble de vos besoins en \u00e9lectricit\u00e9, maintenance et construction. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter Nous Rejoindre Rue des boussines, 42 6960 Manhay Belgique Appelez Nous Bureau +3286321207 Garde +32479268312 Email info@mbssolution.be Heure ouverture Bureau Lun, mar, jeu et ven : 9h \u00e0 16h Mercredi : ferm\u00e9<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder.php","meta":{"footnotes":""},"class_list":["post-228","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - M.B.S group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mbs.group\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - M.B.S group\" \/>\n<meta property=\"og:description\" content=\"MBS Group r\u00e9unit deux entreprises compl\u00e9mentaires pour r\u00e9pondre \u00e0 l\u2019ensemble de vos besoins en \u00e9lectricit\u00e9, maintenance et construction. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter Nous Rejoindre Rue des boussines, 42 6960 Manhay Belgique Appelez Nous Bureau +3286321207 Garde +32479268312 Email info@mbssolution.be Heure ouverture Bureau Lun, mar, jeu et ven : 9h \u00e0 16h Mercredi : ferm\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mbs.group\/\" \/>\n<meta property=\"og:site_name\" content=\"M.B.S group\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T18:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"80\" \/>\n\t<meta property=\"og:image:height\" content=\"78\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mbs.group\\\/\",\"url\":\"https:\\\/\\\/mbs.group\\\/\",\"name\":\"Home - M.B.S group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.group\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mbs.group\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.group\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.group\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/address-icon.png\",\"datePublished\":\"2023-01-11T10:49:13+00:00\",\"dateModified\":\"2026-08-03T18:36:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mbs.group\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mbs.group\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.group\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mbs.group\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/address-icon.png\",\"contentUrl\":\"https:\\\/\\\/mbs.group\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/address-icon.png\",\"width\":80,\"height\":78},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mbs.group\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mbs.group\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mbs.group\\\/#website\",\"url\":\"https:\\\/\\\/mbs.group\\\/\",\"name\":\"M.B.S group\",\"description\":\"M.B.S\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mbs.group\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - M.B.S group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mbs.group\/","og_locale":"fr_FR","og_type":"article","og_title":"Home - M.B.S group","og_description":"MBS Group r\u00e9unit deux entreprises compl\u00e9mentaires pour r\u00e9pondre \u00e0 l\u2019ensemble de vos besoins en \u00e9lectricit\u00e9, maintenance et construction. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter Nous Rejoindre Rue des boussines, 42 6960 Manhay Belgique Appelez Nous Bureau +3286321207 Garde +32479268312 Email info@mbssolution.be Heure ouverture Bureau Lun, mar, jeu et ven : 9h \u00e0 16h Mercredi : ferm\u00e9","og_url":"https:\/\/mbs.group\/","og_site_name":"M.B.S group","article_modified_time":"2026-08-03T18:36:38+00:00","og_image":[{"width":80,"height":78,"url":"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mbs.group\/","url":"https:\/\/mbs.group\/","name":"Home - M.B.S group","isPartOf":{"@id":"https:\/\/mbs.group\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mbs.group\/#primaryimage"},"image":{"@id":"https:\/\/mbs.group\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png","datePublished":"2023-01-11T10:49:13+00:00","dateModified":"2026-08-03T18:36:38+00:00","breadcrumb":{"@id":"https:\/\/mbs.group\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mbs.group\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.group\/#primaryimage","url":"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png","contentUrl":"https:\/\/mbs.group\/wp-content\/uploads\/2023\/01\/address-icon.png","width":80,"height":78},{"@type":"BreadcrumbList","@id":"https:\/\/mbs.group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mbs.group\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/mbs.group\/#website","url":"https:\/\/mbs.group\/","name":"M.B.S group","description":"M.B.S","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mbs.group\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/pages\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/comments?post=228"}],"version-history":[{"count":103,"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/pages\/228\/revisions"}],"predecessor-version":[{"id":549,"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/pages\/228\/revisions\/549"}],"wp:attachment":[{"href":"https:\/\/mbs.group\/index.php\/wp-json\/wp\/v2\/media?parent=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}